{"id":148,"date":"2020-07-01T17:02:33","date_gmt":"2020-07-01T21:02:33","guid":{"rendered":"http:\/\/santateresadelosandes.org\/?p=148"},"modified":"2020-07-13T18:22:32","modified_gmt":"2020-07-13T22:22:32","slug":"08-a-teresa-jaraquemada-astaburuaga-29-de-marzo-de-1916","status":"publish","type":"post","link":"https:\/\/santateresadelosandes.org\/index.php\/2020\/07\/01\/08-a-teresa-jaraquemada-astaburuaga-29-de-marzo-de-1916\/","title":{"rendered":"08. A Teresa Jaraquemada Astaburuaga 29 de marzo de 1916"},"content":{"rendered":"\n<p>Maestranza, marzo 29 de 1916&nbsp;<\/p>\n\n\n\n<p>Se\u00f1orita Teresa Jaraquemada&nbsp;<\/p>\n\n\n\n<p>Mi querida M. Teresa:&nbsp;<\/p>\n\n\n\n<p>Qu\u00e9 sorpresa tan agradable nos trajo tu cartita. Veo que a lo menos te acuerdas de nosotros en Vi\u00f1a, lo que es ya mucho decir. Y nosotros nos acordamos de esa primita tan encantadora que tuvimos en Chacabuco, que nos hizo pasar tan buenos ratos. Desde que t\u00fa te viniste no realizamos paseos bonitos. La Lucita se llevaba tejiendo y no sal\u00eda.&nbsp;<\/p>\n\n\n\n<p>T\u00fa me dices que lo pasas muy bien, de lo que nos alegramos mucho, pues ya sabes lo que yo te deseo: un&#8230; y sobre todo a una prima tan querida. Nosotros estamos muy bien y me parece que saldremos el 22 de abril. As\u00ed es que espero que estar\u00e1s aqu\u00ed para verte. \u00bfVas a ir a Mansel? \u00bfHas sabido de las ni\u00f1itas? \u00bfCu\u00e1ndo entran al colegio&nbsp;<\/p>\n\n\n\n<p>\u00bfY la Julia, c\u00f3mo est\u00e1? Lo pasar\u00e1 muy bien&#8230; La In\u00e9s F. \u00bfEst\u00e1 all\u00e1 en Vi\u00f1a? Si est\u00e1, la saludas. La Lucita fue a Cunaco, donde la Elisita Vald\u00e9s y dijo que te hab\u00eda escrito desde all\u00e1.&nbsp;<\/p>\n\n\n\n<p>Con saludos a mi t\u00eda Elena, abrazos a la Julia, y para ti, mi querida Teruquita, recibe el cari\u00f1o de Rebeca junto con un beso y abrazo de tu&nbsp;<\/p>\n\n\n\n<p>Juana&nbsp;<\/p>\n\n\n\n<p>Dispensa [la] letra, es porque la escribo en un momento libre [y] ya van a tocar&#8230; La Madre Astaburuaga me encarga te salude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maestranza, marzo 29 de 1916&nbsp; Se\u00f1orita Teresa Jaraquemada&nbsp; Mi querida M. Teresa:&nbsp; Qu\u00e9 sorpresa tan agradable nos trajo tu cartita. Veo que a lo menos te acuerdas de nosotros en Vi\u00f1a, lo que es ya mucho decir. Y nosotros nos acordamos de esa primita tan encantadora que tuvimos en Chacabuco, que nos hizo pasar tan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14,4],"tags":[],"_links":{"self":[{"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/posts\/148"}],"collection":[{"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":1,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"predecessor-version":[{"id":149,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/posts\/148\/revisions\/149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/media\/581"}],"wp:attachment":[{"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/santateresadelosandes.org\/index.php\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}